{"id":31,"count":2,"description":"","link":"https:\/\/aaronabelmaldonado.com\/en\/category\/consciencia\/","name":"Consciencia","slug":"consciencia","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/aaronabelmaldonado.com\/en\/wp-json\/wp\/v2\/categories\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aaronabelmaldonado.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/aaronabelmaldonado.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/aaronabelmaldonado.com\/en\/wp-json\/wp\/v2\/posts?categories=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}